{"id":318,"date":"2016-10-31T14:20:44","date_gmt":"2016-10-31T17:20:44","guid":{"rendered":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/?page_id=318"},"modified":"2018-06-22T15:32:23","modified_gmt":"2018-06-22T18:32:23","slug":"contacto","status":"publish","type":"page","link":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/contacto\/","title":{"rendered":"CONTACTO"},"content":{"rendered":"<div  class=\"lgc-column lgc-grid-parent lgc-grid-70 lgc-tablet-grid-60 lgc-mobile-grid-100 lgc-equal-heights \"><div  class=\"inside-grid-column\">\n<h2>Comunicate con nosotros<\/h2>\n<p>\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f57-o1\" lang=\"es-ES\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/sitio\/wp-json\/wp\/v2\/pages\/318#wpcf7-f57-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"57\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.7.7\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f57-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<p><label><b>* Nombre<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-nombre\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-nombre\" \/><\/span><\/label>\n<\/p>\n<p><label><b>* Apellidos<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-apellidos\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-apellidos\" \/><\/span><\/label>\n<\/p>\n<p><label>E-mail<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-e-mail\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-email wpcf7-validates-as-email\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-e-mail\" \/><\/span><\/label>\n<\/p>\n<p><label><b>* Direcci\u00f3n<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-direccion\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-direccion\" \/><\/span><\/label>\n<\/p>\n<p><label><b>* Tel\u00e9fono<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-telefono\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-telefono\" \/><\/span><\/label>\n<\/p>\n<p><label>Ciudad<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-ciudad\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-ciudad\" \/><\/span><\/label>\n<\/p>\n<p><label>C\u00f3digo Postal<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-codigo-postal\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-codigo-postal\" \/><\/span><\/label>\n<\/p>\n<p><label><b>* Provincia<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-provincia\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-provincia\" \/><\/span><\/label>\n<\/p>\n<p><label><b>* Pa\u00eds<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-pais\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"your-pais\"><\/textarea><\/span><\/label>\n<\/p>\n<p><label>Comentarios<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-comentarios\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-comentarios\"><\/textarea><\/span><\/label>\n<\/p>\n<p><label><b>* Sugerencias<\/b><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-sugerencias\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-sugerencias\" \/><\/span><\/label>\n<\/p>\n<p>(*) Los campos son obligatorios.\n<\/p>\n\n<p><input class=\"wpcf7-form-control has-spinner wpcf7-submit\" type=\"submit\" value=\"Enviar\" \/>\n<\/p><p style=\"display: none !important;\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"236\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/p>\n<p><\/p><\/div><\/div>\n<div  class=\"lgc-column lgc-grid-parent lgc-grid-30 lgc-tablet-grid-40 lgc-mobile-grid-100 lgc-equal-heights \"><div  class=\"inside-grid-column\">\n<p><\/p><\/div><\/div><div class=\"lgc-clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/318"}],"collection":[{"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/comments?post=318"}],"version-history":[{"count":6,"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/318\/revisions"}],"predecessor-version":[{"id":642,"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/pages\/318\/revisions\/642"}],"wp:attachment":[{"href":"https:\/\/isfd109-bue.infd.edu.ar\/sitio\/wp-json\/wp\/v2\/media?parent=318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}